{"id":4228,"date":"2022-10-03T13:56:59","date_gmt":"2022-10-03T08:26:59","guid":{"rendered":"https:\/\/lawbhoomi.com\/law-college-search\/?p=4228"},"modified":"2023-11-07T12:12:50","modified_gmt":"2023-11-07T06:42:50","slug":"icfai-law-school-hyderabad","status":"publish","type":"post","link":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/","title":{"rendered":"ICFAI Law School, Hyderabad"},"content":{"rendered":"<h2>Brief Profile of ICFAI Law School, Hyderabad<\/h2>\n<p>The Faculty of Law commonly known as ICFAI Law School is a constituent unit of the ICFAI Foundation for Higher Education (A Deemed-to-be University) established under Section 3 of UGC Act, 1956, located in the lush green environment in the vicinity of historical city of Hyderabad. Today\u2019s legal profession needs a distinctive, well-qualified, analytical legal professional with academic excellence and practical exposure to address complex challenges posed by ever changing business environment.<\/p>\n<p>The ICFAI Law School, with excellent and continuous teaching and learning process, student centric and industry friendly dynamic curriculum and real life exposure provides best in class, legal education to the student and carving them to market ready legal professionals out of mediocre student who desires of making law as the dream career.<\/p>\n<h3>Website<\/h3>\n<p><a href=\"http:\/\/www.ifheindia.org\">www.ifheindia.org<\/a><\/p>\n<h3>Affiliating University<\/h3>\n<p>ICFAI foundation for higher education, hyderabad<\/p>\n<h3>State<\/h3>\n<p>Telangana<\/p>\n<h3>City<\/h3>\n<p>Hyderabad<\/p>\n<h3>Address<\/h3>\n<p>The ICFAI law school, IFHE donathanapally shankarapalli road, Hyderabad, Telangana 501203.<\/p>\n<h3>Government\/Private<\/h3>\n<p>Private<\/p>\n<h3>BCI Approval<\/h3>\n<p>Yes<\/p>\n<h3>Courses Offered<\/h3>\n<ul>\n<li>BALLB<\/li>\n<li>BBA LLB<\/li>\n<li>LLB<\/li>\n<li>LLM<\/li>\n<li>PhD<\/li>\n<\/ul>\n<h3>Email\/Phone<\/h3>\n<p>040-23479725<\/p>\n<p>facultyoflaw@ifheindia.org<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brief Profile of ICFAI Law School, Hyderabad The Faculty of Law commonly known as ICFAI Law School is a constituent unit of the ICFAI Foundation for Higher Education (A Deemed-to-be University) established under Section 3 of UGC Act, 1956, located in the lush green environment in the vicinity of historical city of Hyderabad. Today\u2019s legal &#8230; <a title=\"ICFAI Law School, Hyderabad\" class=\"read-more\" href=\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/\" aria-label=\"Read more about ICFAI Law School, Hyderabad\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":6083,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,10,5,6],"tags":[510,90],"class_list":["post-4228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ballb","category-bballb","category-llb","category-llm","tag-hyderabad","tag-telangana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ICFAI Law School, Hyderabad - Law College Search<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ICFAI Law School, Hyderabad - Law College Search\" \/>\n<meta property=\"og:description\" content=\"Brief Profile of ICFAI Law School, Hyderabad The Faculty of Law commonly known as ICFAI Law School is a constituent unit of the ICFAI Foundation for Higher Education (A Deemed-to-be University) established under Section 3 of UGC Act, 1956, located in the lush green environment in the vicinity of historical city of Hyderabad. Today\u2019s legal ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/\" \/>\n<meta property=\"og:site_name\" content=\"Law College Search\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lawbhoomi\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-03T08:26:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-07T06:42:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/ICFAI-LAW-SCHOOL-HYDERABAD.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Law College Search\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Law College Search\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/\"},\"author\":{\"name\":\"Law College Search\",\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/#\/schema\/person\/703920e4464acc19d64061be308dab2f\"},\"headline\":\"ICFAI Law School, Hyderabad\",\"datePublished\":\"2022-10-03T08:26:59+00:00\",\"dateModified\":\"2023-11-07T06:42:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/\"},\"wordCount\":182,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/#organization\"},\"image\":{\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/ICFAI-LAW-SCHOOL-HYDERABAD.jpg?fit=250%2C250&ssl=1\",\"keywords\":[\"Hyderabad\",\"Telangana\"],\"articleSection\":[\"B.A.LL.B\",\"B.B.A.LL.B.\",\"LL.B.\",\"LL.M.\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/\",\"url\":\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/\",\"name\":\"ICFAI Law School, Hyderabad - Law College Search\",\"isPartOf\":{\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/ICFAI-LAW-SCHOOL-HYDERABAD.jpg?fit=250%2C250&ssl=1\",\"datePublished\":\"2022-10-03T08:26:59+00:00\",\"dateModified\":\"2023-11-07T06:42:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/ICFAI-LAW-SCHOOL-HYDERABAD.jpg?fit=250%2C250&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/ICFAI-LAW-SCHOOL-HYDERABAD.jpg?fit=250%2C250&ssl=1\",\"width\":250,\"height\":250,\"caption\":\"ICFAI Law School, Hyderabad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lawbhoomi.com\/law-college-search\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B.A.LL.B\",\"item\":\"https:\/\/lawbhoomi.com\/law-college-search\/category\/ballb\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ICFAI Law School, Hyderabad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/#website\",\"url\":\"https:\/\/lawbhoomi.com\/law-college-search\/\",\"name\":\"Law College Search\",\"description\":\"Search Law Colleges in India\",\"publisher\":{\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lawbhoomi.com\/law-college-search\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/#organization\",\"name\":\"Law College Search\",\"url\":\"https:\/\/lawbhoomi.com\/law-college-search\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/Law-College-Search-Logo.png?fit=600%2C300&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/Law-College-Search-Logo.png?fit=600%2C300&ssl=1\",\"width\":600,\"height\":300,\"caption\":\"Law College Search\"},\"image\":{\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lawbhoomi\/\",\"https:\/\/www.instagram.com\/lawbhoomi\/\",\"https:\/\/bit.ly\/3O4qP32\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/#\/schema\/person\/703920e4464acc19d64061be308dab2f\",\"name\":\"Law College Search\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lawbhoomi.com\/law-college-search\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/902705f03f60ff84a8b71bd7f7ace2c794668ed12cf02f50534f8b5afa7ff87d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/902705f03f60ff84a8b71bd7f7ace2c794668ed12cf02f50534f8b5afa7ff87d?s=96&d=mm&r=g\",\"caption\":\"Law College Search\"},\"url\":\"https:\/\/lawbhoomi.com\/law-college-search\/author\/content\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ICFAI Law School, Hyderabad - Law College Search","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/","og_locale":"en_US","og_type":"article","og_title":"ICFAI Law School, Hyderabad - Law College Search","og_description":"Brief Profile of ICFAI Law School, Hyderabad The Faculty of Law commonly known as ICFAI Law School is a constituent unit of the ICFAI Foundation for Higher Education (A Deemed-to-be University) established under Section 3 of UGC Act, 1956, located in the lush green environment in the vicinity of historical city of Hyderabad. Today\u2019s legal ... Read more","og_url":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/","og_site_name":"Law College Search","article_publisher":"https:\/\/www.facebook.com\/lawbhoomi\/","article_published_time":"2022-10-03T08:26:59+00:00","article_modified_time":"2023-11-07T06:42:50+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/ICFAI-LAW-SCHOOL-HYDERABAD.jpg","type":"image\/jpeg"}],"author":"Law College Search","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Law College Search","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#article","isPartOf":{"@id":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/"},"author":{"name":"Law College Search","@id":"https:\/\/lawbhoomi.com\/law-college-search\/#\/schema\/person\/703920e4464acc19d64061be308dab2f"},"headline":"ICFAI Law School, Hyderabad","datePublished":"2022-10-03T08:26:59+00:00","dateModified":"2023-11-07T06:42:50+00:00","mainEntityOfPage":{"@id":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/"},"wordCount":182,"commentCount":0,"publisher":{"@id":"https:\/\/lawbhoomi.com\/law-college-search\/#organization"},"image":{"@id":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/ICFAI-LAW-SCHOOL-HYDERABAD.jpg?fit=250%2C250&ssl=1","keywords":["Hyderabad","Telangana"],"articleSection":["B.A.LL.B","B.B.A.LL.B.","LL.B.","LL.M."],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/","url":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/","name":"ICFAI Law School, Hyderabad - Law College Search","isPartOf":{"@id":"https:\/\/lawbhoomi.com\/law-college-search\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#primaryimage"},"image":{"@id":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/ICFAI-LAW-SCHOOL-HYDERABAD.jpg?fit=250%2C250&ssl=1","datePublished":"2022-10-03T08:26:59+00:00","dateModified":"2023-11-07T06:42:50+00:00","breadcrumb":{"@id":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#primaryimage","url":"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/ICFAI-LAW-SCHOOL-HYDERABAD.jpg?fit=250%2C250&ssl=1","contentUrl":"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/ICFAI-LAW-SCHOOL-HYDERABAD.jpg?fit=250%2C250&ssl=1","width":250,"height":250,"caption":"ICFAI Law School, Hyderabad"},{"@type":"BreadcrumbList","@id":"https:\/\/lawbhoomi.com\/law-college-search\/icfai-law-school-hyderabad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lawbhoomi.com\/law-college-search\/"},{"@type":"ListItem","position":2,"name":"B.A.LL.B","item":"https:\/\/lawbhoomi.com\/law-college-search\/category\/ballb\/"},{"@type":"ListItem","position":3,"name":"ICFAI Law School, Hyderabad"}]},{"@type":"WebSite","@id":"https:\/\/lawbhoomi.com\/law-college-search\/#website","url":"https:\/\/lawbhoomi.com\/law-college-search\/","name":"Law College Search","description":"Search Law Colleges in India","publisher":{"@id":"https:\/\/lawbhoomi.com\/law-college-search\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lawbhoomi.com\/law-college-search\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lawbhoomi.com\/law-college-search\/#organization","name":"Law College Search","url":"https:\/\/lawbhoomi.com\/law-college-search\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lawbhoomi.com\/law-college-search\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/Law-College-Search-Logo.png?fit=600%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/Law-College-Search-Logo.png?fit=600%2C300&ssl=1","width":600,"height":300,"caption":"Law College Search"},"image":{"@id":"https:\/\/lawbhoomi.com\/law-college-search\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lawbhoomi\/","https:\/\/www.instagram.com\/lawbhoomi\/","https:\/\/bit.ly\/3O4qP32"]},{"@type":"Person","@id":"https:\/\/lawbhoomi.com\/law-college-search\/#\/schema\/person\/703920e4464acc19d64061be308dab2f","name":"Law College Search","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lawbhoomi.com\/law-college-search\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/902705f03f60ff84a8b71bd7f7ace2c794668ed12cf02f50534f8b5afa7ff87d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/902705f03f60ff84a8b71bd7f7ace2c794668ed12cf02f50534f8b5afa7ff87d?s=96&d=mm&r=g","caption":"Law College Search"},"url":"https:\/\/lawbhoomi.com\/law-college-search\/author\/content\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lawbhoomi.com\/law-college-search\/wp-content\/uploads\/2022\/10\/ICFAI-LAW-SCHOOL-HYDERABAD.jpg?fit=250%2C250&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pedvjz-16c","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/lawbhoomi.com\/law-college-search\/wp-json\/wp\/v2\/posts\/4228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lawbhoomi.com\/law-college-search\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lawbhoomi.com\/law-college-search\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lawbhoomi.com\/law-college-search\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lawbhoomi.com\/law-college-search\/wp-json\/wp\/v2\/comments?post=4228"}],"version-history":[{"count":1,"href":"https:\/\/lawbhoomi.com\/law-college-search\/wp-json\/wp\/v2\/posts\/4228\/revisions"}],"predecessor-version":[{"id":15221,"href":"https:\/\/lawbhoomi.com\/law-college-search\/wp-json\/wp\/v2\/posts\/4228\/revisions\/15221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lawbhoomi.com\/law-college-search\/wp-json\/wp\/v2\/media\/6083"}],"wp:attachment":[{"href":"https:\/\/lawbhoomi.com\/law-college-search\/wp-json\/wp\/v2\/media?parent=4228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lawbhoomi.com\/law-college-search\/wp-json\/wp\/v2\/categories?post=4228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lawbhoomi.com\/law-college-search\/wp-json\/wp\/v2\/tags?post=4228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}